{"id":15695,"date":"2020-04-14T12:26:37","date_gmt":"2020-04-14T15:26:37","guid":{"rendered":"https:\/\/www.megaimagem.com.br\/?p=15695"},"modified":"2024-09-26T11:20:02","modified_gmt":"2024-09-26T14:20:02","slug":"apneia-do-sono-sintomas-e-diagnostico","status":"publish","type":"post","link":"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/","title":{"rendered":"Apneia do sono: sintomas e diagn\u00f3stico"},"content":{"rendered":"<p>A <strong>apneia do sono<\/strong> caracteriza-se pela obstru\u00e7\u00e3o da via a\u00e9rea ao n\u00edvel da garganta durante o sono, levando a uma parada da respira\u00e7\u00e3o, que dura em m\u00e9dia 20 segundos.<\/p>\n<p>Ap\u00f3s esta parada no fluxo de ar para os pulm\u00f5es, o paciente acorda, emitindo um ronco muito ruidoso.<\/p>\n<p>Desta forma, pode ocorrer v\u00e1rias vezes durante a noite, havendo pacientes que apresentam <span class=\"original-content\">uma <\/span>cada um ou dois minutos. Durante estes epis\u00f3dios, a oxigena\u00e7\u00e3o sangu\u00ednea pode cair, expondo o paciente a problemas card\u00edacos.<\/p>\n<h2>Sintomas<\/h2>\n<p>A principal manifesta\u00e7\u00e3o dos problemas cr\u00f4nicos de sono \u00e9 a sonol\u00eancia exagerada.<\/p>\n<p>As primeiras manifesta\u00e7\u00f5es dos dist\u00farbios do sono s\u00e3o as altera\u00e7\u00f5es do humor, da mem\u00f3ria e das capacidades mentais, como aprendizado, racioc\u00ednio, pensamento e concentra\u00e7\u00e3o.<\/p>\n<p>Um sintoma muito caracter\u00edstico de dist\u00farbio de sono \u00e9 o ronco. O ronco ainda hoje \u00e9 interpretado popularmente como sinal de que o indiv\u00edduo dorme bem, mas \u00e9 justamente o contr\u00e1rio.<\/p>\n<p>Quem ronca est\u00e1 esfor\u00e7ando sua musculatura respirat\u00f3ria para al\u00e9m de seus limites, e est\u00e1 sobrecarregando o cora\u00e7\u00e3o de trabalho.<\/p>\n<p>Ao longo do tempo o indiv\u00edduo que ronca pode ficar hipertenso, <span class=\"original-content\">apresentar infarto do mioc\u00e1rdio ou <\/span>derrame cerebral.<\/p>\n<h2>Os principais tipos s\u00e3o:<\/h2>\n<ul>\n<li>Apneia obstrutiva do sono: A forma mais comum que ocorre quando os m\u00fasculos da garganta relaxam<\/li>\n<li>Apneia central do sono: Quando o c\u00e9rebro n\u00e3o envia sinais adequados aos m\u00fasculos que controlam a respira\u00e7\u00e3o.<\/li>\n<li>S\u00edndrome da apneia do sono complexa: Tamb\u00e9m conhecida como <strong>apneia do sono<\/strong> central emergente do tratamento, que ocorre quando algu\u00e9m tem apneia obstrutiva do sono e apneia central do sono.<\/li>\n<\/ul>\n<h2>Causas<\/h2>\n<h3>Apneia obstrutiva do sono<\/h3>\n<p>Isso ocorre quando os m\u00fasculos da parte posterior da garganta relaxam.\u00a0Esses m\u00fasculos sustentam o palato mole, o peda\u00e7o triangular de tecido pendurado no palato mole (\u00favula), as am\u00edgdalas, as paredes laterais da garganta e a l\u00edngua.<\/p>\n<p>Quando os m\u00fasculos relaxam, suas vias a\u00e9reas se estreitam ou fecham conforme voc\u00ea inspira.\u00a0Voc\u00ea n\u00e3o consegue ar suficiente, o que pode diminuir o n\u00edvel de oxig\u00eanio no sangue.<\/p>\n<p>Seu c\u00e9rebro percebe sua incapacidade de respirar e o desperta brevemente do sono para que voc\u00ea possa reabrir suas vias respirat\u00f3rias.\u00a0Esse despertar geralmente \u00e9 t\u00e3o breve que voc\u00ea n\u00e3o se lembra dele.<\/p>\n<p>Voc\u00ea pode bufar, engasgar ou suspirar.\u00a0Esse padr\u00e3o pode se repetir de cinco a 30 vezes ou mais a cada hora, durante toda a noite, prejudicando sua capacidade de atingir as fases profundas e repousantes do sono.<\/p>\n<h3>Apneia central do sono<\/h3>\n<p>Esta forma menos comum de apneia do sono ocorre quando o c\u00e9rebro n\u00e3o consegue transmitir sinais aos m\u00fasculos respirat\u00f3rios.<\/p>\n<p>Isso significa que voc\u00ea n\u00e3o faz nenhum esfor\u00e7o para respirar por um curto per\u00edodo. Voc\u00ea pode acordar com falta de ar ou ter dificuldade em dormir, ou ainda em permanecer dormindo.<\/p>\n<h2>Fatores de risco<\/h2>\n<p>Pode afetar qualquer pessoa, at\u00e9 crian\u00e7as. Mas certos fatores aumentam seu risco.<\/p>\n<h3>Apneia obstrutiva do sono<\/h3>\n<p>Os fatores que aumentam o risco incluem:<\/p>\n<ul>\n<li><strong><a href=\"https:\/\/www.megaimagem.com.br\/blog\/obesidade-o-grande-mal-do-seculo\/\">Excesso de peso<\/a>: <\/strong>A obesidade aumenta muito o risco. Os dep\u00f3sitos de gordura ao redor das vias a\u00e9reas superiores podem obstruir a respira\u00e7\u00e3o;<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Circunfer\u00eancia do pesco\u00e7o: <\/strong>Pessoas com pesco\u00e7o mais grosso podem ter vias a\u00e9reas mais estreitas;<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Uma via a\u00e9rea estreitada:\u00a0 <\/strong>Voc\u00ea pode ter herdado uma garganta estreita.\u00a0As am\u00edgdalas ou adenoides tamb\u00e9m podem aumentar e bloquear as vias a\u00e9reas, principalmente em crian\u00e7as;<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Ser homem: <\/strong>Os homens t\u00eam duas a tr\u00eas vezes mais chances de desenvolverem do que as mulheres. No entanto, as mulheres aumentam o risco se estiverem acima do peso, e o risco tamb\u00e9m parece aumentar ap\u00f3s a menopausa;<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Sendo mais velho: <\/strong>Ocorre com muito mais frequ\u00eancia em adultos mais velhos;<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Hist\u00f3rico familiar: <\/strong>Ter familiares com <strong>apneia do sono<\/strong> pode aumentar o risco;<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Uso de \u00e1lcool, sedativos ou tranq\u00fcilizantes: <\/strong>Essas subst\u00e2ncias relaxam os m\u00fasculos da garganta, o que pode piorar a apneia obstrutiva do sono.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong><a href=\"https:\/\/www.youtube.com\/watch?v=NAcfrRZK-2I\">Tabagismo<\/a>: <\/strong>Os fumantes t\u00eam tr\u00eas vezes mais probabilidade de ter apneia obstrutiva do sono do que as pessoas que nunca fumaram.\u00a0Fumar pode aumentar a quantidade de inflama\u00e7\u00e3o e reten\u00e7\u00e3o de l\u00edquidos nas vias a\u00e9reas superiores;<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Congest\u00e3o nasal: <\/strong>Se voc\u00ea tem dificuldade para respirar pelo nariz &#8211; seja por um problema anat\u00f4mico ou alergia &#8211; \u00e9 prov\u00e1vel que desenvolva apneia obstrutiva do sono;<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Condi\u00e7\u00f5es m\u00e9dicas: <\/strong>Insufici\u00eancia card\u00edaca congestiva, hipertens\u00e3o, <a href=\"https:\/\/www.megaimagem.com.br\/blog\/diabetes-mellitus-qual-a-relacao-com-o-figado\/\">diabetes tipo<\/a> 2 e doen\u00e7a de Parkinson s\u00e3o algumas das condi\u00e7\u00f5es que podem aumentar o risco de apneia obstrutiva do sono.\u00a0A s\u00edndrome do ov\u00e1rio polic\u00edstico, dist\u00farbios hormonais, derrame pr\u00e9vio e doen\u00e7as pulmonares cr\u00f4nicas, como <a href=\"https:\/\/www.megaimagem.com.br\/blog\/saiba-mais-sobre-a-asma\/\">asma<\/a>, tamb\u00e9m podem aumentar o risco.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Apneia central do sono<\/h2>\n<p>Os fatores de risco\u00a0incluem:<\/p>\n<ul>\n<li><strong>Sendo mais velho: <\/strong>Pessoas de meia-idade e mais velhas t\u00eam maior risco<strong>;<\/strong><\/li>\n<li><strong>Ser homem: <\/strong>A apneia central do sono \u00e9 mais comum em homens do que em mulheres;<\/li>\n<li><strong>Dist\u00farbios card\u00edacos: <\/strong>Ter insufici\u00eancia card\u00edaca congestiva aumenta o risco;<\/li>\n<li><strong>Uso de analg\u00e9sicos narc\u00f3ticos: <\/strong>Os medicamentos opioides, especialmente os de a\u00e7\u00e3o prolongada, como a metadona, aumentam o risco de apneia central do sono;<\/li>\n<li><strong>Derrame.\u00a0<\/strong>Ter tido um acidente vascular cerebral aumenta o risco de <strong>apneia do sono<\/strong> central ou apneia do sono central emergente do tratamento.<\/li>\n<\/ul>\n<h2>Complica\u00e7\u00f5es<\/h2>\n<p>A apneia do sono, uma condi\u00e7\u00e3o m\u00e9dica s\u00e9ria, acarreta diversas complica\u00e7\u00f5es significativas. Primeiramente, a fadiga diurna se manifesta devido aos repetidos despertares associados \u00e0 apneia, tornando o sono normal e restaurador imposs\u00edvel.<\/p>\n<p>&nbsp;<\/p>\n<p>Isso resulta em sonol\u00eancia diurna severa, fadiga e irritabilidade, afetando a concentra\u00e7\u00e3o no trabalho, a capacidade de adormecer durante atividades cotidianas como assistir TV e at\u00e9 mesmo durante a condu\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m disso, a press\u00e3o alta ou problemas card\u00edacos representam outra preocupa\u00e7\u00e3o. As quedas repentinas nos n\u00edveis de oxig\u00eanio no sangue durante os epis\u00f3dios de apneia aumentam a press\u00e3o arterial, sobrecarregando o sistema cardiovascular.<\/p>\n<p>&nbsp;<\/p>\n<p>A apneia obstrutiva do sono n\u00e3o apenas eleva o risco de hipertens\u00e3o, mas tamb\u00e9m contribui para ataques card\u00edacos recorrentes, derrames e ritmos card\u00edacos anormais, como fibrila\u00e7\u00e3o atrial, especialmente em indiv\u00edduos com doen\u00e7a card\u00edaca.<\/p>\n<p>&nbsp;<\/p>\n<p>A rela\u00e7\u00e3o entre apneia do sono e diabetes tipo 2 \u00e9 evidente, pois a condi\u00e7\u00e3o aumenta o risco de resist\u00eancia \u00e0 insulina e desenvolvimento da diabetes tipo 2.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m disso, a apneia obstrutiva do sono se torna uma preocupa\u00e7\u00e3o em rela\u00e7\u00e3o a medicamentos e cirurgia, sendo essencial informar os profissionais de sa\u00fade sobre a condi\u00e7\u00e3o antes de procedimentos cir\u00fargicos, pois aumenta a probabilidade de complica\u00e7\u00f5es respirat\u00f3rias.<\/p>\n<p>&nbsp;<\/p>\n<p>Pessoas com apneia do sono tamb\u00e9m enfrentam poss\u00edveis problemas hep\u00e1ticos, com maior probabilidade de resultados anormais nos testes de fun\u00e7\u00e3o hep\u00e1tica e sinais de cicatrizes no f\u00edgado, como na doen\u00e7a hep\u00e1tica gordurosa n\u00e3o-alco\u00f3lica.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m disso, a s\u00edndrome metab\u00f3lica, incluindo press\u00e3o alta, n\u00edveis anormais de colesterol, a\u00e7\u00facar elevado no sangue e aumento da circunfer\u00eancia da cintura, est\u00e1 intrinsecamente relacionada \u00e0 apneia do sono, aumentando o risco global de doen\u00e7as card\u00edacas.<\/p>\n<p>&nbsp;<\/p>\n<h2>Diagn\u00f3stico<\/h2>\n<p><span style=\"font-weight: 400;\">O diagn\u00f3stico <\/span><span style=\"font-weight: 400;\">depende dos sintomas apresentados, podem ser feitos o exame f\u00edsico para ver a garganta, boca e nariz ou pode ser necess\u00e1rios alguns testes em um centro de sono.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Alguns testes incluem a polis sonografia \u2014 nesse exame o paciente ser\u00e1 monitorado durante o sono, sua respira\u00e7\u00e3o, batimentos card\u00edacos, movimentos de pernas e bra\u00e7os, e o n\u00edvel de oxig\u00eanio.\u00a0 <\/span><\/p>\n<h3><strong>Para realizar o tratamento pode ser necess\u00e1rio:\u00a0<\/strong><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">Perda de peso;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> fazer exerc\u00edcios;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> diminuir a ingest\u00e3o de \u00e1lcool;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">diminuir o tabagismo;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> usar medicamentos para descongestionar o nariz ou medicamentos antial\u00e9rgicos;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">n\u00e3o dormir de barriga para cima;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">n\u00e3o usar medicamentos para ansiedade ou p\u00edlulas para dormir.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, pode ser necess\u00e1rio o uso de aparelhos para ajudar a respirar (CPAP). <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entretanto, o CPAP \u00e9 um aparelho que envia um fluxo de ar cont\u00ednuo para as vias respirat\u00f3rias, por meio de uma m\u00e1scara. A quantidade do fluxo de ar enviado \u00e9 determinada pela press\u00e3o informada no exame de polissonografia.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15753 size-full\" src=\"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/aparelho-apneia-e1586786310130.png\" alt=\"apneia-do-sono\" width=\"466\" height=\"410\" srcset=\"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/aparelho-apneia-e1586786310130.png 466w, https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/aparelho-apneia-e1586786310130-300x264.png 300w\" sizes=\"(max-width: 466px) 100vw, 466px\" \/><\/p>\n<p>Podem ser utilizados tamb\u00e9m os dispositivos orais, para casos mais leves.<\/p>\n<p>Em alguns casos podem ser necess\u00e1rias cirurgias, <span class=\"original-content\">como, por exemplo, <\/span>a cirurgia de retirada de tecido da parte posterior da garganta entre outras.<\/p>\n<p>Portanto, caso voc\u00ea apresente algum dos sintomas \u00e9 necess\u00e1rio procurar um m\u00e9dico para realizar o diagn\u00f3stico correto da apneia do sono.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15757 size-full\" src=\"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/aparelho-dentala-e1586809514104.png\" alt=\"apneia-do-sono-aparelho-dental+\" width=\"594\" height=\"484\" srcset=\"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/aparelho-dentala-e1586809514104.png 594w, https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/aparelho-dentala-e1586809514104-300x244.png 300w\" sizes=\"(max-width: 594px) 100vw, 594px\" \/><\/p>\n<h3>Conclus\u00e3o: Enfrentando a Apneia do Sono com Conhecimento e Tratamento Adequado<\/h3>\n<p>Diferentes tipos de apneia do sono, como a obstrutiva e a central, apresentam riscos espec\u00edficos, exigindo uma compreens\u00e3o abrangente e personalizada para o tratamento. Fatores de risco, como excesso de peso, hist\u00f3rico familiar e tabagismo, devem ser considerados ao avaliar a probabilidade de desenvolver a condi\u00e7\u00e3o.<\/p>\n<p>O diagn\u00f3stico preciso \u00e9 fundamental e pode envolver testes como a polissonografia, monitorando diversos aspectos durante o sono. Mas, o tratamento varia desde mudan\u00e7as no estilo de vida, como perda de peso e redu\u00e7\u00e3o do consumo de \u00e1lcool, at\u00e9 o uso de dispositivos como o CPAP, e, em casos mais graves, interven\u00e7\u00f5es cir\u00fargicas.<\/p>\n<p>Portanto, compreender a complexidade da apneia do sono e agir proativamente diante dos sintomas \u00e9 crucial para prevenir complica\u00e7\u00f5es a longo prazo. Dessa forma, Consultar um profissional de sa\u00fade para o diagn\u00f3stico adequado e discutir op\u00e7\u00f5es de tratamento \u00e9 o primeiro passo essencial para enfrentar essa condi\u00e7\u00e3o e promover uma qualidade de vida melhor.<\/p>\n<p><center><center><b><big><\/big><\/b><center><b><big><br \/>\n<\/big><\/b><center><b><big><br \/>\n<\/big><\/b><center><b><big>Agende seus exames aqui na\u00a0<a href=\"https:\/\/agendamento.megaimagem.com.br\/\"><strong>MEGA<\/strong><\/a>. Baixe o MEGAPP! Basta acessar a Play Store ou App Store e baixar o APP que aparece como \u201cMega Imagem-Agendamento\u201d. A Mega sempre pensando em voc\u00ea!<\/big>\u00a0<span class=\"style-scope yt-formatted-string\" dir=\"auto\"><br \/>\n<\/span><\/b><\/center><\/center><\/center><b><big><big><br \/>\n<\/big><big><\/big><\/big><\/b><\/center><\/center><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A apneia do sono caracteriza-se pela obstru\u00e7\u00e3o da via a\u00e9rea ao n\u00edvel da garganta durante o sono, levando a uma parada da respira\u00e7\u00e3o, que dura em m\u00e9dia 20 segundos. Ap\u00f3s esta parada no fluxo de ar para os pulm\u00f5es, o paciente acorda, emitindo um ronco muito ruidoso. Desta forma, pode ocorrer v\u00e1rias vezes durante a [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":15812,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[44,2567,212,2487,324],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Apneia do sono: sintomas e diagn\u00f3stico &#8211; Mega Imagem<\/title>\n<meta name=\"description\" content=\"A apneia do sono \u00e9 a obstru\u00e7\u00e3o da via a\u00e9rea ao n\u00edvel da garganta durante o sono, levando a uma parada da respira\u00e7\u00e3o de 20 segundos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apneia do sono: sintomas e diagn\u00f3stico &#8211; Mega Imagem\" \/>\n<meta property=\"og:description\" content=\"A apneia do sono \u00e9 a obstru\u00e7\u00e3o da via a\u00e9rea ao n\u00edvel da garganta durante o sono, levando a uma parada da respira\u00e7\u00e3o de 20 segundos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/\" \/>\n<meta property=\"og:site_name\" content=\"Mega Imagem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/megaimagemclinica\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-14T15:26:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T14:20:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/apneia-do-sono.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe Mega Imagem\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Mega Imagem\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/\"},\"author\":{\"name\":\"Equipe Mega Imagem\",\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/#\/schema\/person\/c4879ab1e663e64b5d83b218067e8bdb\"},\"headline\":\"Apneia do sono: sintomas e diagn\u00f3stico\",\"datePublished\":\"2020-04-14T15:26:37+00:00\",\"dateModified\":\"2024-09-26T14:20:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/\"},\"wordCount\":1712,\"publisher\":{\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/apneia-do-sono.jpg\",\"keywords\":[\"alimenta\u00e7\u00e3o saud\u00e1vel\",\"qualidade do sono\",\"sa\u00fade da mulher\",\"sa\u00fade do homem\",\"sono\"],\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/\",\"url\":\"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/\",\"name\":\"Apneia do sono: sintomas e diagn\u00f3stico &#8211; Mega Imagem\",\"isPartOf\":{\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/apneia-do-sono.jpg\",\"datePublished\":\"2020-04-14T15:26:37+00:00\",\"dateModified\":\"2024-09-26T14:20:02+00:00\",\"description\":\"A apneia do sono \u00e9 a obstru\u00e7\u00e3o da via a\u00e9rea ao n\u00edvel da garganta durante o sono, levando a uma parada da respira\u00e7\u00e3o de 20 segundos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/#primaryimage\",\"url\":\"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/apneia-do-sono.jpg\",\"contentUrl\":\"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/apneia-do-sono.jpg\",\"width\":700,\"height\":500,\"caption\":\"apneia-do-sono\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.megaimagem.com.br\/wp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apneia do sono: sintomas e diagn\u00f3stico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/#website\",\"url\":\"https:\/\/www.megaimagem.com.br\/wp\/\",\"name\":\"Mega Imagem\",\"description\":\"Diagn\u00f3stico por imagem de alta tecnologia, precis\u00e3o e seguran\u00e7a\",\"publisher\":{\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.megaimagem.com.br\/wp\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/#organization\",\"name\":\"Mega Imagem\",\"url\":\"https:\/\/www.megaimagem.com.br\/wp\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2019\/04\/logo@2x.png\",\"contentUrl\":\"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2019\/04\/logo@2x.png\",\"width\":2001,\"height\":759,\"caption\":\"Mega Imagem\"},\"image\":{\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/megaimagemclinica\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.megaimagem.com.br\/wp\/#\/schema\/person\/c4879ab1e663e64b5d83b218067e8bdb\",\"name\":\"Equipe Mega Imagem\",\"url\":\"https:\/\/www.megaimagem.com.br\/wp\/blog\/author\/bartiraaraujo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apneia do sono: sintomas e diagn\u00f3stico &#8211; Mega Imagem","description":"A apneia do sono \u00e9 a obstru\u00e7\u00e3o da via a\u00e9rea ao n\u00edvel da garganta durante o sono, levando a uma parada da respira\u00e7\u00e3o de 20 segundos.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Apneia do sono: sintomas e diagn\u00f3stico &#8211; Mega Imagem","og_description":"A apneia do sono \u00e9 a obstru\u00e7\u00e3o da via a\u00e9rea ao n\u00edvel da garganta durante o sono, levando a uma parada da respira\u00e7\u00e3o de 20 segundos.","og_url":"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/","og_site_name":"Mega Imagem","article_publisher":"https:\/\/www.facebook.com\/megaimagemclinica","article_published_time":"2020-04-14T15:26:37+00:00","article_modified_time":"2024-09-26T14:20:02+00:00","og_image":[{"width":700,"height":500,"url":"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/apneia-do-sono.jpg","type":"image\/jpeg"}],"author":"Equipe Mega Imagem","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipe Mega Imagem","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/#article","isPartOf":{"@id":"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/"},"author":{"name":"Equipe Mega Imagem","@id":"https:\/\/www.megaimagem.com.br\/wp\/#\/schema\/person\/c4879ab1e663e64b5d83b218067e8bdb"},"headline":"Apneia do sono: sintomas e diagn\u00f3stico","datePublished":"2020-04-14T15:26:37+00:00","dateModified":"2024-09-26T14:20:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/"},"wordCount":1712,"publisher":{"@id":"https:\/\/www.megaimagem.com.br\/wp\/#organization"},"image":{"@id":"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/apneia-do-sono.jpg","keywords":["alimenta\u00e7\u00e3o saud\u00e1vel","qualidade do sono","sa\u00fade da mulher","sa\u00fade do homem","sono"],"articleSection":["Artigos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/","url":"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/","name":"Apneia do sono: sintomas e diagn\u00f3stico &#8211; Mega Imagem","isPartOf":{"@id":"https:\/\/www.megaimagem.com.br\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/#primaryimage"},"image":{"@id":"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/apneia-do-sono.jpg","datePublished":"2020-04-14T15:26:37+00:00","dateModified":"2024-09-26T14:20:02+00:00","description":"A apneia do sono \u00e9 a obstru\u00e7\u00e3o da via a\u00e9rea ao n\u00edvel da garganta durante o sono, levando a uma parada da respira\u00e7\u00e3o de 20 segundos.","breadcrumb":{"@id":"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/#primaryimage","url":"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/apneia-do-sono.jpg","contentUrl":"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2020\/04\/apneia-do-sono.jpg","width":700,"height":500,"caption":"apneia-do-sono"},{"@type":"BreadcrumbList","@id":"https:\/\/www.megaimagem.com.br\/wp\/blog\/apneia-do-sono-sintomas-e-diagnostico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.megaimagem.com.br\/wp\/"},{"@type":"ListItem","position":2,"name":"Apneia do sono: sintomas e diagn\u00f3stico"}]},{"@type":"WebSite","@id":"https:\/\/www.megaimagem.com.br\/wp\/#website","url":"https:\/\/www.megaimagem.com.br\/wp\/","name":"Mega Imagem","description":"Diagn\u00f3stico por imagem de alta tecnologia, precis\u00e3o e seguran\u00e7a","publisher":{"@id":"https:\/\/www.megaimagem.com.br\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.megaimagem.com.br\/wp\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.megaimagem.com.br\/wp\/#organization","name":"Mega Imagem","url":"https:\/\/www.megaimagem.com.br\/wp\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.megaimagem.com.br\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2019\/04\/logo@2x.png","contentUrl":"https:\/\/www.megaimagem.com.br\/wp\/wp-content\/uploads\/2019\/04\/logo@2x.png","width":2001,"height":759,"caption":"Mega Imagem"},"image":{"@id":"https:\/\/www.megaimagem.com.br\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/megaimagemclinica"]},{"@type":"Person","@id":"https:\/\/www.megaimagem.com.br\/wp\/#\/schema\/person\/c4879ab1e663e64b5d83b218067e8bdb","name":"Equipe Mega Imagem","url":"https:\/\/www.megaimagem.com.br\/wp\/blog\/author\/bartiraaraujo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.megaimagem.com.br\/wp\/wp-json\/wp\/v2\/posts\/15695"}],"collection":[{"href":"https:\/\/www.megaimagem.com.br\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.megaimagem.com.br\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.megaimagem.com.br\/wp\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.megaimagem.com.br\/wp\/wp-json\/wp\/v2\/comments?post=15695"}],"version-history":[{"count":15,"href":"https:\/\/www.megaimagem.com.br\/wp\/wp-json\/wp\/v2\/posts\/15695\/revisions"}],"predecessor-version":[{"id":34655,"href":"https:\/\/www.megaimagem.com.br\/wp\/wp-json\/wp\/v2\/posts\/15695\/revisions\/34655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.megaimagem.com.br\/wp\/wp-json\/wp\/v2\/media\/15812"}],"wp:attachment":[{"href":"https:\/\/www.megaimagem.com.br\/wp\/wp-json\/wp\/v2\/media?parent=15695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.megaimagem.com.br\/wp\/wp-json\/wp\/v2\/categories?post=15695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.megaimagem.com.br\/wp\/wp-json\/wp\/v2\/tags?post=15695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}